{"id":513,"count":1,"description":"","link":"https:\/\/egydesigner.com\/blog\/tag\/%d8%a3%d9%88%d9%85\/","name":"\u0623\u0648\u0645","slug":"%d8%a3%d9%88%d9%85","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/egydesigner.com\/blog\/tag\/%d8%a3%d9%88%d9%85\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/egydesigner.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/513\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/egydesigner.com\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/egydesigner.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/egydesigner.com\\\/blog\\\/tag\\\/%d8%a3%d9%88%d9%85\\\/#listItem\",\"name\":\"\\u0623\\u0648\\u0645\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/egydesigner.com\\\/blog\\\/tag\\\/%d8%a3%d9%88%d9%85\\\/#listItem\",\"position\":2,\"name\":\"\\u0623\\u0648\\u0645\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/egydesigner.com\\\/blog#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/egydesigner.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/513\\\/#collectionpage\",\"url\":\"https:\\\/\\\/egydesigner.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/513\\\/\",\"name\":\"\\u0623\\u0648\\u0645 - EGY DESIGNER BLOG\",\"inLanguage\":\"ar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/egydesigner.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/egydesigner.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/513\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/egydesigner.com\\\/blog\\\/#organization\",\"name\":\"EGY designer\",\"description\":\"\\u0627\\u0644\\u0631\\u0643\\u0646 \\u0627\\u0644\\u0625\\u0639\\u0644\\u0627\\u0645\\u0649 \\u0648\\u0627\\u0644\\u0645\\u0639\\u0644\\u0648\\u0645\\u0627\\u062a\\u064a\",\"url\":\"https:\\\/\\\/egydesigner.com\\\/blog\\\/\",\"email\":\"info@egydesigner.com\",\"telephone\":\"+20225176921\",\"foundingDate\":\"2007-01-15\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":50,\"maxValue\":50},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/egydesigner.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-APP-2.png\",\"@id\":\"https:\\\/\\\/egydesigner.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/513\\\/#organizationLogo\",\"width\":512,\"height\":512,\"caption\":\"egy designer logo\"},\"image\":{\"@id\":\"https:\\\/\\\/egydesigner.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/513\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/egydesigner.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/egydesigner.com\\\/blog\\\/\",\"name\":\"EGY DESIGNER BLOG\",\"alternateName\":\"\\u0627\\u0644\\u0631\\u0643\\u0646 \\u0627\\u0644\\u0625\\u0639\\u0644\\u0627\\u0645\\u0649 \\u0648\\u0627\\u0644\\u0645\\u0639\\u0644\\u0648\\u0645\\u0627\\u062a\\u064a\",\"description\":\"\\u0627\\u0644\\u0631\\u0643\\u0646 \\u0627\\u0644\\u0625\\u0639\\u0644\\u0627\\u0645\\u0649 \\u0648\\u0627\\u0644\\u0645\\u0639\\u0644\\u0648\\u0645\\u0627\\u062a\\u064a\",\"inLanguage\":\"ar\",\"publisher\":{\"@id\":\"https:\\\/\\\/egydesigner.com\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u0623\u0648\u0645 - EGY DESIGNER BLOG","description":"","canonical_url":"https:\/\/egydesigner.com\/blog\/tag\/%d8%a3%d9%88%d9%85\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/egydesigner.com\/blog\/wp-json\/wp\/v2\/tags\/513\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/egydesigner.com\/blog#listItem","position":1,"name":"Home","item":"https:\/\/egydesigner.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/egydesigner.com\/blog\/tag\/%d8%a3%d9%88%d9%85\/#listItem","name":"\u0623\u0648\u0645"}},{"@type":"ListItem","@id":"https:\/\/egydesigner.com\/blog\/tag\/%d8%a3%d9%88%d9%85\/#listItem","position":2,"name":"\u0623\u0648\u0645","previousItem":{"@type":"ListItem","@id":"https:\/\/egydesigner.com\/blog#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/egydesigner.com\/blog\/wp-json\/wp\/v2\/tags\/513\/#collectionpage","url":"https:\/\/egydesigner.com\/blog\/wp-json\/wp\/v2\/tags\/513\/","name":"\u0623\u0648\u0645 - EGY DESIGNER BLOG","inLanguage":"ar","isPartOf":{"@id":"https:\/\/egydesigner.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/egydesigner.com\/blog\/wp-json\/wp\/v2\/tags\/513\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/egydesigner.com\/blog\/#organization","name":"EGY designer","description":"\u0627\u0644\u0631\u0643\u0646 \u0627\u0644\u0625\u0639\u0644\u0627\u0645\u0649 \u0648\u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a\u064a","url":"https:\/\/egydesigner.com\/blog\/","email":"info@egydesigner.com","telephone":"+20225176921","foundingDate":"2007-01-15","numberOfEmployees":{"@type":"QuantitativeValue","minValue":50,"maxValue":50},"logo":{"@type":"ImageObject","url":"https:\/\/egydesigner.com\/blog\/wp-content\/uploads\/2018\/09\/cropped-APP-2.png","@id":"https:\/\/egydesigner.com\/blog\/wp-json\/wp\/v2\/tags\/513\/#organizationLogo","width":512,"height":512,"caption":"egy designer logo"},"image":{"@id":"https:\/\/egydesigner.com\/blog\/wp-json\/wp\/v2\/tags\/513\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/egydesigner.com\/blog\/#website","url":"https:\/\/egydesigner.com\/blog\/","name":"EGY DESIGNER BLOG","alternateName":"\u0627\u0644\u0631\u0643\u0646 \u0627\u0644\u0625\u0639\u0644\u0627\u0645\u0649 \u0648\u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a\u064a","description":"\u0627\u0644\u0631\u0643\u0646 \u0627\u0644\u0625\u0639\u0644\u0627\u0645\u0649 \u0648\u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a\u064a","inLanguage":"ar","publisher":{"@id":"https:\/\/egydesigner.com\/blog\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/egydesigner.com\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u0623\u0648\u0645\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/egydesigner.com\/blog"},{"label":"\u0623\u0648\u0645","link":"https:\/\/egydesigner.com\/blog\/tag\/%d8%a3%d9%88%d9%85\/"}],"_links":{"self":[{"href":"https:\/\/egydesigner.com\/blog\/wp-json\/wp\/v2\/tags\/513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/egydesigner.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/egydesigner.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/egydesigner.com\/blog\/wp-json\/wp\/v2\/posts?tags=513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}